{"id":1139,"date":"2021-06-17T16:20:13","date_gmt":"2021-06-17T14:20:13","guid":{"rendered":"https:\/\/seriousfactory.com\/blog\/?p=1139"},"modified":"2025-08-22T15:23:00","modified_gmt":"2025-08-22T13:23:00","slug":"minimalisme-digital-learning-2021","status":"publish","type":"post","link":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/","title":{"rendered":"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?"},"content":{"rendered":"<h3>Le minimalisme, qu\u2019est-ce que c\u2019est ?<\/h3>\n<p>Lorsque l\u2019on pense au minimalisme, on pense automatiquement \u00e0 la catchphrase \u00ab Less is more \u00bb. Il est peu probable que vous n\u2019ayez jamais entendu parler de ce concept, tant il est d\u00e9sormais ancr\u00e9 dans le mode de vie de beaucoup de personnes et dans divers domaines tels que l\u2019architecture et la cuisine. Et pourtant, il touche d\u00e9sormais aussi le domaine de la formation professionnelle.<\/p>\n<p>Int\u00e9grer le concept du minimalisme dans la formation revient \u00e0 ne garder que l\u2019essentiel lors de sa conception. Lors de pr\u00e9c\u00e9dents articles, nous vous avons parl\u00e9 d\u2019apporter l\u2019effet \u00ab Whaou ! \u00bb dans vos conceptions avec <strong>des m\u00e9canismes emprunt\u00e9s au jeu vid\u00e9o<\/strong> et en mettant<strong> l\u2019accent sur l\u2019univers graphique<\/strong>. Cet effet peut \u00eatre tr\u00e8s efficace pour assurer une bonne r\u00e9tention de l\u2019information. Cependant, l\u2019effet \u00ab Whaou ! \u00bb doit \u00eatre utilis\u00e9 en compl\u00e9ment d\u2019un travail r\u00e9alis\u00e9 pr\u00e9alablement sur le fond, car celui-ci ne peut compenser d\u2019\u00e9ventuelles faiblesses techniques.<\/p>\n<p>Ainsi, en gardant l\u2019essentiel de la formation, c\u2019est-\u00e0-dire les informations importantes \u00e0 retenir, le tout enrob\u00e9 dans une exp\u00e9rience graphiquement simple et \u00e9pur\u00e9e, que vous \u00e9viterez toute surcharge cognitive lors de l\u2019exercice et que la r\u00e9tention sera favoris\u00e9e. <strong>L\u2019effort doit \u00eatre focalis\u00e9 sur le fond pour laisser de la place \u00e0 la r\u00e9flexion<\/strong>, comme on le ferait pour du <a href=\"https:\/\/seriousfactory.com\/fr\/formation\/formation-vtseditor-introduction-variables-foad-inter-entreprise\/?origin=old_blog\">Microlearning<\/a>.<\/p>\n<h3>Cr\u00e9er des formations minimalistes avec VTS, c\u2019est possible !<\/h3>\n<p>En plus de permettre une conception simplifi\u00e9e gr\u00e2ce aux blocs intelligents, <strong>VTS Editor poss\u00e8de un catalogue de personnages r\u00e9alistes et de d\u00e9cors pr\u00eats \u00e0 l\u2019emploi<\/strong>, d\u00e8s la version d\u2019essai.<\/p>\n<p>Afin d&rsquo;int\u00e9grer le minimalisme dans vos formations, nous vous conseillons ces bonnes pratiques \u00e0 mettre en place sur le logiciel auteur :<br \/>\n&#8211; <strong>Travailler l\u2019\u00e9quilibre action\/r\u00e9flexion<\/strong>, en ponctuant les p\u00e9riodes de concentration par de courts exercices<br \/>\n&#8211; <strong>Ne pas surcharger l\u2019espace cognitif de l\u2019apprenant<\/strong> en utilisant trop de personnages ou trop de d\u00e9cors<br \/>\n&#8211; <strong>Faire des mises en sc\u00e8ne simples<\/strong> en \u00e9vitant de passer incessamment d\u2019une sc\u00e8ne \u00e0 l\u2019autre<br \/>\n&#8211; <strong>Faire dire l\u2019essentiel aux personnages<\/strong><\/p>\n<p><a href=\"https:\/\/seriousfactory.com\/telecharger-vts-editor\/\"><img decoding=\"async\" class=\"aligncenter wp-image-8090 size-full\" src=\"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2018\/12\/Bouton-editor-fr.png\" alt=\"\" width=\"268\" height=\"53\" \/><\/a><\/p>\n<div class=\"learn-more-box\" style=\"margin-top:2em;padding:1em 1.2em;border:1px solid #e5e7eb;border-radius:10px;\">\n<h2 style=\"margin:0 0 .5em 0;font-size:1.2em;\">Liens utiles<\/h2>\n<ul>\n<li><a href=\"https:\/\/seriousfactory.com\/fr\/solutions-elearning\/serious-games\/?origin=old_blog\">Outil e\u2011learning IA<\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Graphismes pouss\u00e9s, animations, interactivit\u00e9, ajout de m\u00e9dias\u2026 Nous avons tendance \u00e0 penser que la formation professionnelle a besoin d&rsquo;utiliser diverses techniques de conception avanc\u00e9es pour \u00eatre attractive, engageante et m\u00e9morable pour l\u2019apprenant. Et si le contraire \u00e9tait aussi vrai en 2021 ? Coup de projecteur sur le minimalisme en formation digitale.<\/strong><\/p>\n","protected":false},"author":12,"featured_media":1140,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_focuskw":"minimalisme formation","_yoast_wpseo_title":"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?","_yoast_wpseo_metadesc":"Graphismes pouss\u00e9s, animations, interactivit\u00e9, ajout de m\u00e9dias\u2026 Nous avons tendance \u00e0 penser que la formation professionnelle a besoin de tous ces enrobages pour \u00eatre attractive, engageante et m\u00e9morable pour l\u2019apprenant. Et si le contraire \u00e9tait aussi vrai en 2021 ? Coup de projecteur sur le minimalisme en formation digitale.","footnotes":""},"categories":[1029],"tags":[17,265,27],"class_list":["post-1139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elearning","tag-digital-learning","tag-elearning","tag-vts-editor"],"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"_thumbnail_id":"1140","_yoast_wpseo_twitter-description":null,"_yoast_wpseo_twitter-title":null,"_yoast_wpseo_twitter-image":null,"_product_image_gallery":"","_yoast_wpseo_focuskw":"minimalisme formation","_yoast_wpseo_title":"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?","_yoast_wpseo_metadesc":"Graphismes pouss\u00e9s, animations, interactivit\u00e9, ajout de m\u00e9dias\u2026 Nous avons tendance \u00e0 penser que la formation professionnelle a besoin de tous ces enrobages pour \u00eatre attractive, engageante et m\u00e9morable pour l\u2019apprenant. Et si le contraire \u00e9tait aussi vrai en 2021 ? Coup de projecteur sur le minimalisme en formation digitale.","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?<\/title>\n<meta name=\"description\" content=\"Graphismes pouss\u00e9s, animations, interactivit\u00e9, ajout de m\u00e9dias\u2026 Nous avons tendance \u00e0 penser que la formation professionnelle a besoin de tous ces enrobages pour \u00eatre attractive, engageante et m\u00e9morable pour l\u2019apprenant. Et si le contraire \u00e9tait aussi vrai en 2021 ? Coup de projecteur sur le minimalisme en formation digitale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?\" \/>\n<meta property=\"og:description\" content=\"Graphismes pouss\u00e9s, animations, interactivit\u00e9, ajout de m\u00e9dias\u2026 Nous avons tendance \u00e0 penser que la formation professionnelle a besoin de tous ces enrobages pour \u00eatre attractive, engageante et m\u00e9morable pour l\u2019apprenant. Et si le contraire \u00e9tait aussi vrai en 2021 ? Coup de projecteur sur le minimalisme en formation digitale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Serious Factory\u2019s latest news\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T14:20:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-22T13:23:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2021\/06\/Article_minimalisme.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"William PERES\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Serious_Factory\" \/>\n<meta name=\"twitter:site\" content=\"@Serious_Factory\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"William PERES\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/\"},\"author\":{\"name\":\"William PERES\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#\\\/schema\\\/person\\\/ff78c4739fe0285ca74f732e8b46bd09\"},\"headline\":\"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?\",\"datePublished\":\"2021-06-17T14:20:13+00:00\",\"dateModified\":\"2025-08-22T13:23:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/\"},\"wordCount\":392,\"publisher\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Article_minimalisme.jpg\",\"keywords\":[\"digital learning\",\"elearning\",\"vts editor\"],\"articleSection\":[\"E-learning\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/\",\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/\",\"name\":\"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Article_minimalisme.jpg\",\"datePublished\":\"2021-06-17T14:20:13+00:00\",\"dateModified\":\"2025-08-22T13:23:00+00:00\",\"description\":\"Graphismes pouss\u00e9s, animations, interactivit\u00e9, ajout de m\u00e9dias\u2026 Nous avons tendance \u00e0 penser que la formation professionnelle a besoin de tous ces enrobages pour \u00eatre attractive, engageante et m\u00e9morable pour l\u2019apprenant. Et si le contraire \u00e9tait aussi vrai en 2021 ? Coup de projecteur sur le minimalisme en formation digitale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Article_minimalisme.jpg\",\"contentUrl\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Article_minimalisme.jpg\",\"width\":1170,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/minimalisme-digital-learning-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/\",\"name\":\"Serious Factory - Blog\",\"description\":\"Bienvenue sur le blog de Serious Factory, votre page d&#039;accueil pour les ressources p\u00e9dagogiques, les derni\u00e8res actualit\u00e9s de Serious Factory et plus encore \",\"publisher\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#organization\",\"name\":\"Serious Factory\",\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-LOGO_SF_HORIZONTAL_FOND_BLANC.png\",\"contentUrl\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-LOGO_SF_HORIZONTAL_FOND_BLANC.png\",\"width\":756,\"height\":296,\"caption\":\"Serious Factory\"},\"image\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Serious_Factory\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/serious-factory\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCphbp65IJZIspwX3R_dEY3w\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#\\\/schema\\\/person\\\/ff78c4739fe0285ca74f732e8b46bd09\",\"name\":\"William PERES\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g\",\"caption\":\"William PERES\"},\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/author\\\/wperesseriousfactory-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?","description":"Graphismes pouss\u00e9s, animations, interactivit\u00e9, ajout de m\u00e9dias\u2026 Nous avons tendance \u00e0 penser que la formation professionnelle a besoin de tous ces enrobages pour \u00eatre attractive, engageante et m\u00e9morable pour l\u2019apprenant. Et si le contraire \u00e9tait aussi vrai en 2021 ? Coup de projecteur sur le minimalisme en formation digitale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?","og_description":"Graphismes pouss\u00e9s, animations, interactivit\u00e9, ajout de m\u00e9dias\u2026 Nous avons tendance \u00e0 penser que la formation professionnelle a besoin de tous ces enrobages pour \u00eatre attractive, engageante et m\u00e9morable pour l\u2019apprenant. Et si le contraire \u00e9tait aussi vrai en 2021 ? Coup de projecteur sur le minimalisme en formation digitale.","og_url":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/","og_site_name":"Serious Factory\u2019s latest news","article_published_time":"2021-06-17T14:20:13+00:00","article_modified_time":"2025-08-22T13:23:00+00:00","og_image":[{"width":1170,"height":400,"url":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2021\/06\/Article_minimalisme.jpg","type":"image\/jpeg"}],"author":"William PERES","twitter_card":"summary_large_image","twitter_creator":"@Serious_Factory","twitter_site":"@Serious_Factory","twitter_misc":{"\u00c9crit par":"William PERES","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/#article","isPartOf":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/"},"author":{"name":"William PERES","@id":"https:\/\/seriousfactory.com\/blog\/#\/schema\/person\/ff78c4739fe0285ca74f732e8b46bd09"},"headline":"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?","datePublished":"2021-06-17T14:20:13+00:00","dateModified":"2025-08-22T13:23:00+00:00","mainEntityOfPage":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/"},"wordCount":392,"publisher":{"@id":"https:\/\/seriousfactory.com\/blog\/#organization"},"image":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2021\/06\/Article_minimalisme.jpg","keywords":["digital learning","elearning","vts editor"],"articleSection":["E-learning"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/","url":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/","name":"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?","isPartOf":{"@id":"https:\/\/seriousfactory.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/#primaryimage"},"image":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2021\/06\/Article_minimalisme.jpg","datePublished":"2021-06-17T14:20:13+00:00","dateModified":"2025-08-22T13:23:00+00:00","description":"Graphismes pouss\u00e9s, animations, interactivit\u00e9, ajout de m\u00e9dias\u2026 Nous avons tendance \u00e0 penser que la formation professionnelle a besoin de tous ces enrobages pour \u00eatre attractive, engageante et m\u00e9morable pour l\u2019apprenant. Et si le contraire \u00e9tait aussi vrai en 2021 ? Coup de projecteur sur le minimalisme en formation digitale.","breadcrumb":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/#primaryimage","url":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2021\/06\/Article_minimalisme.jpg","contentUrl":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2021\/06\/Article_minimalisme.jpg","width":1170,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/seriousfactory.com\/blog\/fr\/minimalisme-digital-learning-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seriousfactory.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Le minimalisme, une bonne id\u00e9e pour le Digital Learning en 2021 ?"}]},{"@type":"WebSite","@id":"https:\/\/seriousfactory.com\/blog\/#website","url":"https:\/\/seriousfactory.com\/blog\/","name":"Serious Factory - Blog","description":"Bienvenue sur le blog de Serious Factory, votre page d&#039;accueil pour les ressources p\u00e9dagogiques, les derni\u00e8res actualit\u00e9s de Serious Factory et plus encore ","publisher":{"@id":"https:\/\/seriousfactory.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seriousfactory.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/seriousfactory.com\/blog\/#organization","name":"Serious Factory","url":"https:\/\/seriousfactory.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/seriousfactory.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2023\/12\/cropped-LOGO_SF_HORIZONTAL_FOND_BLANC.png","contentUrl":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2023\/12\/cropped-LOGO_SF_HORIZONTAL_FOND_BLANC.png","width":756,"height":296,"caption":"Serious Factory"},"image":{"@id":"https:\/\/seriousfactory.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Serious_Factory","https:\/\/www.linkedin.com\/company\/serious-factory\/","https:\/\/www.youtube.com\/channel\/UCphbp65IJZIspwX3R_dEY3w"]},{"@type":"Person","@id":"https:\/\/seriousfactory.com\/blog\/#\/schema\/person\/ff78c4739fe0285ca74f732e8b46bd09","name":"William PERES","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g","caption":"William PERES"},"url":"https:\/\/seriousfactory.com\/blog\/author\/wperesseriousfactory-com\/"}]}},"_links":{"self":[{"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/posts\/1139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/comments?post=1139"}],"version-history":[{"count":3,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/posts\/1139\/revisions"}],"predecessor-version":[{"id":6902,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/posts\/1139\/revisions\/6902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/media\/1140"}],"wp:attachment":[{"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/media?parent=1139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/categories?post=1139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/tags?post=1139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}