{"id":1042,"date":"2020-09-11T11:45:14","date_gmt":"2020-09-11T09:45:14","guid":{"rendered":"https:\/\/seriousfactory.com\/blog\/?p=1042"},"modified":"2025-08-22T14:24:08","modified_gmt":"2025-08-22T12:24:08","slug":"serious-factory-serious-game-process-communication-model-kahler-communications","status":"publish","type":"post","link":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/","title":{"rendered":"Serious Factory r\u00e9alise le premier serious game sur  Process Communication Model\u00ae pour Kahler Communications"},"content":{"rendered":"<p>Le groupe Kahler Communications, distributeur mondial de la m\u00e9thode Process Communication Model\u00ae (PCM), souhaitait sensibiliser ses formateurs, coachs et utilisateurs finaux \u00e0 son mod\u00e8le au moyen d\u2019un outil digital innovant qui int\u00e8gre des m\u00e9canismes de gamification et d\u2019apprentissage par essai\/erreur. Convaincues par l\u2019expertise en digital learning et serious gaming de Serious Factory, KCF a s\u00e9lectionn\u00e9 l\u2019\u00e9diteur et sa solution logicielle Virtual Training Suite (VTS) pour ce projet ambitieux, ce qui d\u00e9montre, une fois encore, que le digital est au service de l\u2019humain.<\/p>\n<h3>Process Communication Model\u00ae<\/h3>\n<p>C\u2019est en partenariat avec la NASA, qui souhaitait pr\u00e9parer les \u00e9quipages d\u2019astronautes \u00e0 mieux travailler ensemble, que le mod\u00e8le PCM cr\u00e9\u00e9 par le Docteur en psychologie Taibi Kahler a connu son d\u00e9veloppement initial. Premier mod\u00e8le bas\u00e9 sur l\u2019observation des comportements, PCM est \u00e0 la fois un mod\u00e8le de personnalit\u00e9 et de communication qui permet de d\u00e9velopper la connaissance de soi et des autres, et d\u2019optimiser les relations au quotidien. Il s\u2019est rapidement impos\u00e9 dans le monde entier comme un outil essentiel pour l\u2019entreprise autant que pour les familles. PCM est le seul mod\u00e8le qui propose \u00e0 la fois d\u2019identifier, de pr\u00e9venir et d\u2019\u00e9viter les malentendus st\u00e9riles et parfois destructeurs du quotidien, gr\u00e2ce \u00e0 une meilleure connaissance des profils de personnalit\u00e9 et la pr\u00e9visibilit\u00e9 des comportements sous stress.<\/p>\n<h3>Un outil digital pour am\u00e9liorer les relations humaines<\/h3>\n<p>La formation PCM repose donc sur l\u2019humain et la communication. Alors comment le digital peut-il y avoir sa place ? C\u2019\u00e9tait l\u00e0 l\u2019un des enjeux majeurs de ce projet. En collaborant \u00e9troitement avec KCF, Serious Factory a propos\u00e9 une exp\u00e9rience tr\u00e8s engageante pour les utilisateurs, au moyen d\u2019un <a href=\"https:\/\/seriousfactory.com\/fr\/solutions-elearning\/modules-e-learning-gamifies\/?origin=old_blog\">serious game<\/a> sur-mesure qui m\u00eale avec succ\u00e8s d\u00e9cors 3D immersifs et personnages r\u00e9alistes ainsi que signaux verbaux et non-verbaux.<\/p>\n<p>En mettant sur pied une \u00e9quipe compos\u00e9e d\u2019experts Process Communication Model de Kahler Communications et d\u2019experts en gamification de Serious Factory, la co-cr\u00e9ation p\u00e9dagogique et digitale a \u00e9t\u00e9 un r\u00e9el succ\u00e8s. Tant pour ce qui est de la pertinence et du r\u00e9alisme des situations, que pour l\u2019engagement de l\u2019apprenant gr\u00e2ce \u00e0 un environnement ludique, graphique et innovant.<\/p>\n<h3>Plus que jamais, on apprend en faisant !<\/h3>\n<p>Pour Micka\u00ebl Dufourneaud, Directeur des op\u00e9rations de Kahler Communications, \u00ab Je ne m\u2019attendais pas \u00e0 un tel r\u00e9sultat. Je me suis R\u00c9-GA-L\u00c9 ! J\u2019en ai presque oubli\u00e9 que les interactions des personnages dans leurs environnements sont virtuelles. G\u00e9nial d\u2019avoir un outil qui permet \u00e0 chacun d\u2019avancer \u00e0 son rythme dans la d\u00e9couverte de PCM, pour mieux communiquer et g\u00e9rer les situations d\u00e9licates \u00bb.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-7050\" src=\"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2020\/09\/kcf.png\" alt=\"\" width=\"700\" height=\"396\" \/><\/p>\n<p style=\"text-align: center;\"><em>Illustration d\u2019une sc\u00e8ne dans PCM Virtual Learning<\/em><\/p>\n<h3>Un <a href=\"https:\/\/seriousfactory.com\/fr\/abonnement-freelance\/?origin=old_blog\">serious game<\/a> unique pour des usages vari\u00e9s<\/h3>\n<p>L\u2019autre enjeu fort \u00e9tait de proposer une solution adapt\u00e9e \u00e0 deux cibles : les apprenants et les formateurs et coachs certifi\u00e9s. C\u2019est ainsi que le serious game d\u00e9velopp\u00e9 est propos\u00e9 aux apprenants, soit en vue de pr\u00e9parer leur formation ou leur coaching, soit en renforcement des acquis. Il est \u00e9galement propos\u00e9 au r\u00e9seau des certifi\u00e9s PCM en tant que support innovant d\u2019animation ou de coaching.<\/p>\n<p>Pour que ce dispositif p\u00e9dagogique r\u00e9ponde pleinement \u00e0 ces deux enjeux, la prise en compte de \u00ab l\u2019exp\u00e9rience utilisateur \u00bb et de \u00ab l\u2019exp\u00e9rience apprenant \u00bb a \u00e9t\u00e9 primordiale. Tout au long du parcours de conception du serious game, des certifi\u00e9s PCM et des apprenants ont pu tester les diff\u00e9rentes \u00e9tapes cl\u00e9s, de telle sorte que le r\u00e9sultat soit r\u00e9aliste et refl\u00e8te des sc\u00e8nes de la vie courante et qui auraient tr\u00e8s bien pu se produire.<\/p>\n<p>Le serious game permet donc d\u2019am\u00e9liorer sensiblement l\u2019offre du r\u00e9seau et de renforcer la valeur ajout\u00e9e des certifi\u00e9s PCM dans leur c\u0153ur de m\u00e9tier.<br \/>\nPour Cyril Collignon, Pr\u00e9sident du groupe Kahler Communications, \u00ab Le travail de grande qualit\u00e9 r\u00e9alis\u00e9 par les \u00e9quipes de Serious Factory va nous permettre d\u2019am\u00e9liorer notre dynamique d\u2019animation de notre r\u00e9seau des certifi\u00e9s PCM et de leurs clients. \u00c0 l\u2019\u00e8re de la digitalisation \u00e0 marche forc\u00e9e, nous avons su construire ensemble un outil p\u00e9dagogique innovant, parfait pour s\u2019entra\u00eener \u00e0 g\u00e9rer les relations humaines au quotidien. Un bel outil pour s\u2019entrainer \u00e0 faire passer nos messages dans le confort du test and learn. \u00bb<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone wp-image-7053\" src=\"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2020\/09\/Coach.jpg\" alt=\"\" width=\"700\" height=\"467\" \/><\/p>\n<p style=\"text-align: center;\"><em>Coaching \u00e0 distance en utilisant PCM Virtual Learning<\/em><\/p>\n<h3>Un d\u00e9ploiement international en toute s\u00e9r\u00e9nit\u00e9<\/h3>\n<p>Enfin, pour \u00eatre en phase avec sa dimension internationale et notamment le march\u00e9 anglophone (USA en priorit\u00e9), le serious game sera prochainement disponible en anglais. Il est par ailleurs d\u00e9ploy\u00e9 sur la plateforme VTS Perform de Serious Factory, ce qui permet une administration globale par Kahler Communications et la collecte d\u2019informations pr\u00e9cieuses \u00e0 travers des statistiques qualitatives avanc\u00e9es.<\/p>\n<p>En effet, en ce qui concerne les relations interpersonnelles, la remont\u00e9e de statistiques riches et exploitables est un atout consid\u00e9rable de VTS Perform. \u00c0 l\u2019heure ou la data contribue \u00e0 l\u2019am\u00e9lioration du quotidien de mani\u00e8re croissante, toutes les variables et d\u00e9roul\u00e9s des diff\u00e9rentes situations du serious game remontent au sein de la plateforme, ce qui permet \u00e0 Kahler Communications d\u2019exploiter et de constituer des rapports pr\u00e9cis des usages et de suivi de l\u2019acquisition des comp\u00e9tences des apprenants.<br \/>\nDisponible sur VTS Player, le serious game peut \u00eatre jou\u00e9 sur tout type de p\u00e9riph\u00e9rique (PC, tablette, smartphone), connect\u00e9 ou non \u00e0 Internet.<\/p>\n<div class=\"learn-more-box\" style=\"margin-top:2em;padding:1em 1.2em;border:1px solid #e5e7eb;border-radius:10px;\">\n<h2 style=\"margin:0 0 .5em 0;font-size:1.2em;\">Liens utiles<\/h2>\n<ul>\n<li><a href=\"https:\/\/seriousfactory.com\/fr\/solutions-elearning\/serious-games\/?origin=old_blog\">Conception Serious game<\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><strong>Kahler Communications, sp\u00e9cialiste du d\u00e9veloppement personnel a choisi Serious Factory, leader EdTech du digital learning, pour r\u00e9aliser PCM Virtual Learning, son serious game destin\u00e9 \u00e0 faire d\u00e9couvrir son mod\u00e8le d\u2019optimisation de la relation aux autres.<\/strong><\/p>\n","protected":false},"author":12,"featured_media":1043,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[887],"tags":[265,209,267,25,27],"class_list":["post-1042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendances-du-digital-learning","tag-elearning","tag-innovation-pedagogique","tag-kcf","tag-serious-game","tag-vts-editor"],"_elementor_source_image_hash":null,"_wp_attachment_image_alt":null,"_thumbnail_id":"1043","_yoast_wpseo_twitter-description":null,"_yoast_wpseo_twitter-title":null,"_yoast_wpseo_twitter-image":null,"_product_image_gallery":"1041,1040,1044","_yoast_wpseo_focuskw":"Kahler Communications serious game","_yoast_wpseo_title":"Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications","_yoast_wpseo_metadesc":"Kahler Communications, sp\u00e9cialiste du d\u00e9veloppement personnel a choisi Serious Factory pour r\u00e9aliser PCM Virtual Learning, son serious game destin\u00e9 \u00e0 faire d\u00e9couvrir son mod\u00e8le d\u2019optimisation de la relation aux autres.","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications<\/title>\n<meta name=\"description\" content=\"Kahler Communications, sp\u00e9cialiste du d\u00e9veloppement personnel a choisi Serious Factory pour r\u00e9aliser PCM Virtual Learning, son serious game destin\u00e9 \u00e0 faire d\u00e9couvrir son mod\u00e8le d\u2019optimisation de la relation aux autres.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications\" \/>\n<meta property=\"og:description\" content=\"Kahler Communications, sp\u00e9cialiste du d\u00e9veloppement personnel a choisi Serious Factory pour r\u00e9aliser PCM Virtual Learning, son serious game destin\u00e9 \u00e0 faire d\u00e9couvrir son mod\u00e8le d\u2019optimisation de la relation aux autres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/\" \/>\n<meta property=\"og:site_name\" content=\"Serious Factory\u2019s latest news\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-11T09:45:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-22T12:24:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2020\/09\/KCF-Virtual-Training-Suite.jpg\" \/>\n<meta name=\"author\" content=\"William PERES\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Serious_Factory\" \/>\n<meta name=\"twitter:site\" content=\"@Serious_Factory\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"William PERES\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/\"},\"author\":{\"name\":\"William PERES\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#\\\/schema\\\/person\\\/ff78c4739fe0285ca74f732e8b46bd09\"},\"headline\":\"Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications\",\"datePublished\":\"2020-09-11T09:45:14+00:00\",\"dateModified\":\"2025-08-22T12:24:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/\"},\"wordCount\":972,\"publisher\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/KCF_article.jpg\",\"keywords\":[\"elearning\",\"innovation p\u00e9dagogique\",\"KCF\",\"serious game\",\"vts editor\"],\"articleSection\":[\"Tendances du digital learning\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/\",\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/\",\"name\":\"Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/KCF_article.jpg\",\"datePublished\":\"2020-09-11T09:45:14+00:00\",\"dateModified\":\"2025-08-22T12:24:08+00:00\",\"description\":\"Kahler Communications, sp\u00e9cialiste du d\u00e9veloppement personnel a choisi Serious Factory pour r\u00e9aliser PCM Virtual Learning, son serious game destin\u00e9 \u00e0 faire d\u00e9couvrir son mod\u00e8le d\u2019optimisation de la relation aux autres.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/#primaryimage\",\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/KCF_article.jpg\",\"contentUrl\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/KCF_article.jpg\",\"width\":1170,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/fr\\\/serious-factory-serious-game-process-communication-model-kahler-communications\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/\",\"name\":\"Serious Factory - Blog\",\"description\":\"Bienvenue sur le blog de Serious Factory, votre page d&#039;accueil pour les ressources p\u00e9dagogiques, les derni\u00e8res actualit\u00e9s de Serious Factory et plus encore \",\"publisher\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#organization\",\"name\":\"Serious Factory\",\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-LOGO_SF_HORIZONTAL_FOND_BLANC.png\",\"contentUrl\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-LOGO_SF_HORIZONTAL_FOND_BLANC.png\",\"width\":756,\"height\":296,\"caption\":\"Serious Factory\"},\"image\":{\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/Serious_Factory\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/serious-factory\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCphbp65IJZIspwX3R_dEY3w\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/#\\\/schema\\\/person\\\/ff78c4739fe0285ca74f732e8b46bd09\",\"name\":\"William PERES\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g\",\"caption\":\"William PERES\"},\"url\":\"https:\\\/\\\/seriousfactory.com\\\/blog\\\/author\\\/wperesseriousfactory-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications","description":"Kahler Communications, sp\u00e9cialiste du d\u00e9veloppement personnel a choisi Serious Factory pour r\u00e9aliser PCM Virtual Learning, son serious game destin\u00e9 \u00e0 faire d\u00e9couvrir son mod\u00e8le d\u2019optimisation de la relation aux autres.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/","og_locale":"fr_FR","og_type":"article","og_title":"Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications","og_description":"Kahler Communications, sp\u00e9cialiste du d\u00e9veloppement personnel a choisi Serious Factory pour r\u00e9aliser PCM Virtual Learning, son serious game destin\u00e9 \u00e0 faire d\u00e9couvrir son mod\u00e8le d\u2019optimisation de la relation aux autres.","og_url":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/","og_site_name":"Serious Factory\u2019s latest news","article_published_time":"2020-09-11T09:45:14+00:00","article_modified_time":"2025-08-22T12:24:08+00:00","og_image":[{"url":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2020\/09\/KCF-Virtual-Training-Suite.jpg","type":"","width":"","height":""}],"author":"William PERES","twitter_card":"summary_large_image","twitter_creator":"@Serious_Factory","twitter_site":"@Serious_Factory","twitter_misc":{"\u00c9crit par":"William PERES","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/#article","isPartOf":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/"},"author":{"name":"William PERES","@id":"https:\/\/seriousfactory.com\/blog\/#\/schema\/person\/ff78c4739fe0285ca74f732e8b46bd09"},"headline":"Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications","datePublished":"2020-09-11T09:45:14+00:00","dateModified":"2025-08-22T12:24:08+00:00","mainEntityOfPage":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/"},"wordCount":972,"publisher":{"@id":"https:\/\/seriousfactory.com\/blog\/#organization"},"image":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/#primaryimage"},"thumbnailUrl":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2020\/09\/KCF_article.jpg","keywords":["elearning","innovation p\u00e9dagogique","KCF","serious game","vts editor"],"articleSection":["Tendances du digital learning"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/","url":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/","name":"Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications","isPartOf":{"@id":"https:\/\/seriousfactory.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/#primaryimage"},"image":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/#primaryimage"},"thumbnailUrl":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2020\/09\/KCF_article.jpg","datePublished":"2020-09-11T09:45:14+00:00","dateModified":"2025-08-22T12:24:08+00:00","description":"Kahler Communications, sp\u00e9cialiste du d\u00e9veloppement personnel a choisi Serious Factory pour r\u00e9aliser PCM Virtual Learning, son serious game destin\u00e9 \u00e0 faire d\u00e9couvrir son mod\u00e8le d\u2019optimisation de la relation aux autres.","breadcrumb":{"@id":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/#primaryimage","url":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2020\/09\/KCF_article.jpg","contentUrl":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2020\/09\/KCF_article.jpg","width":1170,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/seriousfactory.com\/blog\/fr\/serious-factory-serious-game-process-communication-model-kahler-communications\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/seriousfactory.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Serious Factory r\u00e9alise le premier serious game sur Process Communication Model\u00ae pour Kahler Communications"}]},{"@type":"WebSite","@id":"https:\/\/seriousfactory.com\/blog\/#website","url":"https:\/\/seriousfactory.com\/blog\/","name":"Serious Factory - Blog","description":"Bienvenue sur le blog de Serious Factory, votre page d&#039;accueil pour les ressources p\u00e9dagogiques, les derni\u00e8res actualit\u00e9s de Serious Factory et plus encore ","publisher":{"@id":"https:\/\/seriousfactory.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seriousfactory.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/seriousfactory.com\/blog\/#organization","name":"Serious Factory","url":"https:\/\/seriousfactory.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/seriousfactory.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2023\/12\/cropped-LOGO_SF_HORIZONTAL_FOND_BLANC.png","contentUrl":"https:\/\/seriousfactory.com\/blog\/wp-content\/uploads\/2023\/12\/cropped-LOGO_SF_HORIZONTAL_FOND_BLANC.png","width":756,"height":296,"caption":"Serious Factory"},"image":{"@id":"https:\/\/seriousfactory.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/Serious_Factory","https:\/\/www.linkedin.com\/company\/serious-factory\/","https:\/\/www.youtube.com\/channel\/UCphbp65IJZIspwX3R_dEY3w"]},{"@type":"Person","@id":"https:\/\/seriousfactory.com\/blog\/#\/schema\/person\/ff78c4739fe0285ca74f732e8b46bd09","name":"William PERES","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c684d6135ed099ab9b9389fe4ef0021e26cfe180f949a1c3f4433ac9d0000d06?s=96&d=mm&r=g","caption":"William PERES"},"url":"https:\/\/seriousfactory.com\/blog\/author\/wperesseriousfactory-com\/"}]}},"_links":{"self":[{"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/posts\/1042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/comments?post=1042"}],"version-history":[{"count":2,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/posts\/1042\/revisions"}],"predecessor-version":[{"id":6879,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/posts\/1042\/revisions\/6879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/media\/1043"}],"wp:attachment":[{"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/media?parent=1042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/categories?post=1042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/seriousfactory.com\/blog\/wp-json\/wp\/v2\/tags?post=1042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}